{"id":14856,"date":"2023-01-04T08:47:15","date_gmt":"2023-01-04T07:47:15","guid":{"rendered":"https:\/\/fondation-grenoble-inp.fr\/?p=14856"},"modified":"2023-07-24T15:04:26","modified_gmt":"2023-07-24T13:04:26","slug":"mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp","status":"publish","type":"post","link":"https:\/\/fondation-grenoble-inp.fr\/en\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/","title":{"rendered":"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14856\" data-post-id=\"14856\" data-obj-id=\"14856\" class=\"elementor elementor-14856 dce-elementor-post-14856\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4359bb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4359bb1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8286bce\" data-id=\"8286bce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f15219 elementor-widget elementor-widget-text-editor\" data-id=\"9f15219\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Depuis 2014, gr\u00e2ce au m\u00e9c\u00e9nat de comp\u00e9tences, la Fondation Grenoble INP attire l\u2019expertise des entreprises industrielles au b\u00e9n\u00e9fice des \u00e9tudiants de <a href=\"https:\/\/www.grenoble-inp.fr\/\" target=\"_blank\" rel=\"noopener\">Grenoble INP \u2013 UGA<\/a>. Dans ce cadre, le cabinet de conseil <a href=\"https:\/\/macs.consulting\/\" target=\"_blank\" rel=\"noopener\">MACS consulting<\/a> participe \u00e0 l&rsquo;animation des cours de <a href=\"https:\/\/genie-industriel.grenoble-inp.fr\/\" target=\"_blank\" rel=\"noopener\">Grenoble INP &#8211; G\u00e9nie Industriel, UGA<\/a> depuis septembre 2022.<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-308ba57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"308ba57\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a0fd5f\" data-id=\"9a0fd5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baaedc0 elementor-widget elementor-widget-text-editor\" data-id=\"baaedc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>Une collaboration au profit des \u00e9l\u00e8ves ing\u00e9nieurs<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76bf4ab elementor-widget elementor-widget-text-editor\" data-id=\"76bf4ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>MACS Consulting est un cabinet lyonnais de conseil, sp\u00e9cialis\u00e9 en Supply Chain, et en Performance des Op\u00e9rations. Sa mission est d\u2019acc\u00e9l\u00e9rer la transformation des entreprises industrielles et de les accompagner dans le changement. MACS intervient dans tous les secteurs de l\u2019industrie, de la PME au grand groupe, en France comme \u00e0 l\u2019international.<\/p><p>Dans sa d\u00e9marche de m\u00e9c\u00e9nat et plus particuli\u00e8rement de soutien des \u00e9tablissements d\u2019enseignement sup\u00e9rieur, MACS consulting collabore avec la Fondation Grenoble INP sous forme de m\u00e9c\u00e9nat de comp\u00e9tences. La soci\u00e9t\u00e9 apporte son expertise avec un soutien humain \u00e0 la Fondation aux b\u00e9n\u00e9fices de ses \u00e9coles, de ses laboratoires et ses \u00e9tudiants. 3 de ses salari\u00e9s (experts, ing\u00e9nieurs) interviennent donc 10 jours par an au profit de Grenoble INP \u2013 G\u00e9nie industriel, UGA.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff0f2a9 elementor-widget elementor-widget-text-editor\" data-id=\"ff0f2a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><em> \u00ab\u00a0MACS participe \u00e0 l\u2019animation de mon cours de 3\u1d49 ann\u00e9e \u00e0 Grenoble INP &#8211; G\u00e9nie Industriel, UGA, Tactical and operational supply chain management. Dans ce cours, nous animons ensemble plusieurs \u00e9tudes de cas, construites \u00e0 partir de cas r\u00e9els industriels. Ces probl\u00e9matiques complexes et multifactorielles sont fortement appr\u00e9ci\u00e9es par des \u00e9l\u00e8ves, de m\u00eame que l\u2019approche ludique par l\u2019essai-erreur que nous avons mis en place. Par leurs exp\u00e9riences du terrain, les avis des experts de MACS sur les solutions propos\u00e9es par les \u00e9l\u00e8ves apportent une valeur ajout\u00e9e vis-\u00e0-vis de la faisabilit\u00e9 des solutions. Les experts racontent \u00e9galement de nombreuses anecdotes des projets industriels qu&rsquo;ils ont men\u00e9s pour alimenter les discussions. Tout cela permet d\u2019aborder des m\u00e9thodes essentielles en G\u00e9nie industriel et d\u2019aller au-del\u00e0 des exercices purement th\u00e9oriques.\u00a0\u00bb <\/em> <cite><strong><a href=\"https:\/\/www.linkedin.com\/in\/g%C3%BClg%C3%BCn-alpan-95910765\/\" target=\"_blank\" rel=\"noopener\">G\u00fclg\u00fcn Alpan<\/a><\/strong>, Professeure \u00e0 Grenoble INP &#8211; G\u00e9nie Industriel, UGA <\/cite><\/blockquote>\n<!-- \/wp:quote -->\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a02ef95 elementor-widget elementor-widget-text-editor\" data-id=\"a02ef95\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\">\n<p><em>\u00ab\u00a0Macs Consulting est heureux d\u2019honorer sa premi\u00e8re ann\u00e9e de m\u00e9c\u00e9nat de comp\u00e9tences avec Grenoble INP. Anciens el\u00e8ves issus de g\u00e9nie industriel, pour certains d\u2019entre nous, nous avons le plaisir d\u2019entretenir nos relations avec les enseignants et les futurs ing\u00e9nieurs en venant y dispenser des cours, transmettre nos exp\u00e9riences terrain et apporter notre vision professionnelle de la Supply Chain. <\/em><\/p>\n<p><em>\u00a0<\/em><em>En intervenant aupr\u00e8s des \u00e9tudiants de l\u2019Ecole, nous avons pour objectif de transmettre la r\u00e9alit\u00e9 des probl\u00e9matiques industrielles actuelles. Nos cours sont bas\u00e9es sur des \u00e9tudes de cas concr\u00e8tes, issues de missions r\u00e9alis\u00e9es chez nos clients. Le but est que les \u00e9tudiants soient le mieux pr\u00e9par\u00e9s pour travailler demain dans le monde de la supply chain. Les derni\u00e8res crises mondiales ont mis en \u00e9vidence des sujets trop longtemps ignor\u00e9s par certains industriels : sourcing low cost vs internalisation d\u2019activit\u00e9, int\u00e9gration des \u00e9missions carbone dans les choix strat\u00e9giques, r\u00e9silience et flexibilit\u00e9\u2026 Les futurs dipl\u00f4m\u00e9s de G\u00e9nie industriel devront trouver les solutions autour de ces sujets ! <\/em><\/p>\n<p><em>\u00a0<\/em><em>Ce partenariat nous apporte \u00e9galement deux atouts majeurs : L\u2019opportunit\u00e9 de d\u00e9tecter les futurs potentiels et passionn\u00e9s par ces probl\u00e9matiques, pour venir enrichir nos \u00e9quipes de consultants ; et pour nos consultants actuels, s\u2019exercer \u00e0 la formation, d\u2019une part \u00e0 la pr\u00e9paration des supports et des \u00e9tudes de cas, et d\u2019autre part \u00e0 l\u2019animation et la transmission de nos outils et m\u00e9thodes.\u00a0\u00bb<\/em> <cite><strong><a href=\"https:\/\/www.linkedin.com\/in\/sebastien-raba-971a8815\/\" target=\"_blank\" rel=\"noopener\">S\u00e9bastien Raba<\/a><\/strong>, Directeur G\u00e9n\u00e9ral Associ\u00e9 &#8211; MACS Consulting<\/p>\n<\/blockquote>\n<!-- \/wp:quote -->\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-843e53f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"843e53f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fa10cd\" data-id=\"6fa10cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3050c7 elementor-widget elementor-widget-text-editor\" data-id=\"b3050c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>\u00c0 propos du m\u00e9c\u00e9nat de comp\u00e9tences<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7c91ab elementor-widget elementor-widget-text-editor\" data-id=\"c7c91ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>En m\u00e9c\u00e9nat de comp\u00e9tences, la contribution humaine de l\u2019entreprise \u00e0 la Fondation, et par son interm\u00e9diaire aux \u00e9coles de Grenoble INP &#8211; UGA, se concr\u00e9tise par la mise \u00e0 disposition d\u2019un ou plusieurs collaborateur(s) \u2013 experts, ing\u00e9nieurs \u2013 qui interviennent \u00e0 titre r\u00e9gulier dans les cycles de formation, les chaires de recherche, les manifestations \u00e9v\u00e9nementielles. Une convention pluriannuelle est sign\u00e9e entre l\u2019entreprise et la Fondation. Les parties s\u2019entendent, en coordination avec l\u2019\u00e9cole, sur le ou les intervenants, la ou les formations concern\u00e9es, le volume horaire et la th\u00e9matique \u00e0 aborder. Leur mission est red\u00e9finie chaque ann\u00e9e, pour correspondre au mieux \u00e0 l\u2019\u00e9volution des technologies, des m\u00e9tiers.<\/p><p>Les interventions sont li\u00e9es aux programmes de formation. Ainsi, les \u00e9l\u00e8ves disposent non seulement des comp\u00e9tences de l\u2019\u00e9quipe p\u00e9dagogique de l\u2019\u00e9cole, mais aussi des comp\u00e9tences pratiques des experts qui participent \u00e0 l\u2019animation des ateliers. Les intervenants apportent une \u201cvision industrie\u201d aux \u00e9tudiants de Grenoble INP &#8211; UGA, qui pr\u00e9figure leur avenir dans l\u2019entreprise.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbe640c elementor-widget elementor-widget-text-editor\" data-id=\"dbe640c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><!-- wp:quote --><\/p><blockquote class=\"wp-block-quote\"><p><em> \u00ab C\u2019est la dimension humaine qui fait la force de ce dispositif. C\u2019est pourquoi nous pla\u00e7ons le m\u00e9c\u00e9nat de comp\u00e9tences comme un \u00e9l\u00e9ment fort de nos relations partenariales avec les entreprises.\u00a0\u00bb <\/em><\/p><p><cite><strong><a href=\"https:\/\/www.linkedin.com\/in\/murielle-brachotte-50359951\/\" target=\"_blank\" rel=\"noopener\">Murielle Brachotte<\/a><\/strong>, Directrice adjointe de la Fondation Grenoble INP<\/cite><\/p><\/blockquote><p>\u00a0<\/p><p><!-- \/wp:quote --><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Le cabinet de conseil MACS consulting participe \u00e0 l&rsquo;animation des cours de Grenoble INP &#8211; G\u00e9nie Industriel, UGA depuis septembre 2022.<\/p>","protected":false},"author":7,"featured_media":14857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[475],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP - Fondation Grenoble INP<\/title>\n<meta name=\"description\" content=\"Le cabinet de conseil MACS consulting participe \u00e0 l&#039;animation des cours de Grenoble INP - G\u00e9nie Industriel, UGA depuis septembre 2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondation-grenoble-inp.fr\/en\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP - Fondation Grenoble INP\" \/>\n<meta property=\"og:description\" content=\"Le cabinet de conseil MACS consulting participe \u00e0 l&#039;animation des cours de Grenoble INP - G\u00e9nie Industriel, UGA depuis septembre 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondation-grenoble-inp.fr\/en\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Grenoble INP\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T07:47:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T13:04:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Dubreuil\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\",\"name\":\"Fondation INP Grenoble\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"width\":512,\"height\":512,\"caption\":\"Fondation INP Grenoble\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"name\":\"Fondation Grenoble INP\",\"description\":\"#OsezlAvenir\",\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg\",\"width\":\"2560\",\"height\":\"1707\",\"caption\":\"MACS Consulting\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#webpage\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/\",\"name\":\"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP - Fondation Grenoble INP\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#primaryimage\"},\"datePublished\":\"2023-01-04T07:47:15+00:00\",\"dateModified\":\"2023-07-24T13:04:26+00:00\",\"description\":\"Le cabinet de conseil MACS consulting participe \u00e0 l'animation des cours de Grenoble INP - G\u00e9nie Industriel, UGA depuis septembre 2022.\",\"breadcrumb\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fondation-grenoble-inp.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94\"},\"headline\":\"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP\",\"datePublished\":\"2023-01-04T07:47:15+00:00\",\"dateModified\":\"2023-07-24T13:04:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#webpage\"},\"wordCount\":880,\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg\",\"articleSection\":[\"La Fondation\"],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94\",\"name\":\"Marie Dubreuil\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g\",\"caption\":\"Marie Dubreuil\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP - Fondation Grenoble INP","description":"Le cabinet de conseil MACS consulting participe \u00e0 l'animation des cours de Grenoble INP - G\u00e9nie Industriel, UGA depuis septembre 2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondation-grenoble-inp.fr\/en\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP - Fondation Grenoble INP","og_description":"Le cabinet de conseil MACS consulting participe \u00e0 l'animation des cours de Grenoble INP - G\u00e9nie Industriel, UGA depuis septembre 2022.","og_url":"https:\/\/fondation-grenoble-inp.fr\/en\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/","og_site_name":"Fondation Grenoble INP","article_published_time":"2023-01-04T07:47:15+00:00","article_modified_time":"2023-07-24T13:04:26+00:00","og_image":[{"width":"2560","height":"1707","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marie Dubreuil","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fondation-grenoble-inp.fr\/#organization","name":"Fondation INP Grenoble","url":"https:\/\/fondation-grenoble-inp.fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#logo","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","width":512,"height":512,"caption":"Fondation INP Grenoble"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/fondation-grenoble-inp.fr\/#website","url":"https:\/\/fondation-grenoble-inp.fr\/","name":"Fondation Grenoble INP","description":"#OsezlAvenir","publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#primaryimage","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg","width":"2560","height":"1707","caption":"MACS Consulting"},{"@type":"WebPage","@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#webpage","url":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/","name":"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP - Fondation Grenoble INP","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#primaryimage"},"datePublished":"2023-01-04T07:47:15+00:00","dateModified":"2023-07-24T13:04:26+00:00","description":"Le cabinet de conseil MACS consulting participe \u00e0 l'animation des cours de Grenoble INP - G\u00e9nie Industriel, UGA depuis septembre 2022.","breadcrumb":{"@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fondation-grenoble-inp.fr\/"},{"@type":"ListItem","position":2,"name":"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP"}]},{"@type":"Article","@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#article","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#webpage"},"author":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94"},"headline":"M\u00e9c\u00e9nat de comp\u00e9tences : MACS Consulting intervient au sein de Grenoble INP","datePublished":"2023-01-04T07:47:15+00:00","dateModified":"2023-07-24T13:04:26+00:00","mainEntityOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#webpage"},"wordCount":880,"publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/mecenat-de-competences-macs-consulting-intervient-au-sein-de-grenoble-inp\/#primaryimage"},"thumbnailUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/01\/IMG_7838-scaled.jpg","articleSection":["La Fondation"],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94","name":"Marie Dubreuil","image":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g","caption":"Marie Dubreuil"}}]}},"_links":{"self":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/14856"}],"collection":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/comments?post=14856"}],"version-history":[{"count":14,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/14856\/revisions"}],"predecessor-version":[{"id":14890,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/14856\/revisions\/14890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media\/14857"}],"wp:attachment":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media?parent=14856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/categories?post=14856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/tags?post=14856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}