{"id":16554,"date":"2023-10-11T11:09:03","date_gmt":"2023-10-11T09:09:03","guid":{"rendered":"https:\/\/fondation-grenoble-inp.fr\/?p=16554"},"modified":"2023-10-30T12:09:18","modified_gmt":"2023-10-30T11:09:18","slug":"le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president","status":"publish","type":"post","link":"https:\/\/fondation-grenoble-inp.fr\/en\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/","title":{"rendered":"Le Conseil d&rsquo;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16554\" data-post-id=\"16554\" data-obj-id=\"16554\" class=\"elementor elementor-16554 dce-elementor-post-16554\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d10501f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d10501f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f4e1dc\" data-id=\"4f4e1dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf1b9ee elementor-widget elementor-widget-text-editor\" data-id=\"cf1b9ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Depuis bient\u00f4t 15 ans, la <a href=\"https:\/\/fondation-grenoble-inp.fr\/en\/\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\">Grenoble INP Foundation<\/a> a pour mission de soutenir l\u2019ambition et le d\u00e9veloppement de <a href=\"https:\/\/www.grenoble-inp.fr\/\" target=\"_blank\" rel=\"noopener\">Grenoble INP \u2013 UGA<\/a> (Institut d\u2019ing\u00e9nierie et de management de l\u2019Universit\u00e9 Grenoble Alpes), afin de construire le monde de demain et de faire rayonner l\u2019excellence acad\u00e9mique et scientifique de l\u2019\u00e9tablissement jusqu\u2019\u00e0 l\u2019international. En 2023, <a href=\"https:\/\/www.linkedin.com\/in\/nicolas-leterrier-7b965545\/\" target=\"_blank\" rel=\"noopener\">Nicolas Leterrier<\/a>, Responsable des partenariats externes &#8211; Innovation et technologie chez <a href=\"https:\/\/www.se.com\/fr\/fr\/\" target=\"_blank\" rel=\"noopener\">Schneider Electric<\/a>, a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation. <a href=\"https:\/\/www.linkedin.com\/in\/laurent-perotin-2782b4a2\/\" target=\"_blank\" rel=\"noopener\">Laurent Perotin<\/a>, Directeur Performance d\u2019Exploitation chez <a href=\"https:\/\/www.edf.fr\/groupe-edf\/produire-une-energie-respectueuse-du-climat\/accelerer-le-developpement-des-energies-renouvelables\/lenergie-hydraulique\/les-avantages-de-lhydroelectricite\" target=\"_blank\" rel=\"noopener\">EDF Hydro<\/a>, a quant \u00e0 lui pris le relais de <a href=\"https:\/\/www.linkedin.com\/in\/gilles-feuillade-82689a13a\/\" target=\"_blank\" rel=\"noopener\">Gilles Feuillade<\/a> en tant que vice-pr\u00e9sident. Nous les avons rencontr\u00e9s pour discuter de leurs motivations, des accomplissements de la Fondation et de leurs ambitions pour l&rsquo;avenir.<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe170a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe170a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2859d30\" data-id=\"2859d30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a6c16d elementor-widget elementor-widget-text-editor\" data-id=\"8a6c16d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>Qu&rsquo;est-ce qui vous a motiv\u00e9 \u00e0 vous engager au sein de la Fondation Grenoble INP ?<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb9ccc elementor-widget elementor-widget-text-editor\" data-id=\"3bb9ccc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Nicolas Leterrier :<\/strong> J\u2019ai eu la chance de faire partie du petit groupe qui a particip\u00e9 \u00e0 la cr\u00e9ation de la <br \/>Fondation Grenoble INP en 2010. Ce qui m&rsquo;a motiv\u00e9, c\u2019\u00e9tait la vision de soutenir l\u2019ambition commune de <strong><a href=\"https:\/\/www.grenoble-inp.fr\/\" target=\"_blank\" rel=\"noopener\">Grenoble INP \u2013 UGA<\/a><\/strong>, qui consiste \u00e0 encourager l&rsquo;excellence et \u00e0 accompagner les \u00e9tudiants dans des choix parfois complexes. Nous voulons les aider \u00e0 concr\u00e9tiser leurs projets de vie et de formation d&rsquo;ing\u00e9nieur, ainsi qu&rsquo;\u00e0 atteindre les carri\u00e8res qu&rsquo;ils d\u00e9sirent, m\u00eame si elles leur sont encore inconnues. Tout cela repose sur des \u00e9changes humains, des rencontres et des opportunit\u00e9s. En tant que personne, je souhaite apporter conseils et \u00e9clairages \u00e0 ces jeunes.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5be613b elementor-widget elementor-widget-text-editor\" data-id=\"5be613b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Laurent Perotin :<\/strong> Moi-m\u00eame dipl\u00f4m\u00e9 de <strong><a href=\"https:\/\/ense3.grenoble-inp.fr\/\" target=\"_blank\" rel=\"noopener\">Grenoble INP &#8211; Ense<sup>3<\/sup>, UGA<\/a><\/strong>, j\u2019assure la pr\u00e9sidence du Conseil de l\u2019\u00e9cole depuis 2019. Je suis \u00e9galement membre du Conseil d\u2019Administration de Grenoble INP &#8211; UGA depuis 2019 et membre du Conseil d\u2019Administration de la <strong><a href=\"https:\/\/fondation-grenoble-inp.fr\/en\/\" target=\"_blank\" rel=\"noopener\">Grenoble INP Foundation<\/a><\/strong> depuis 2020. Ce qui m\u2019a motiv\u00e9 \u00e0 m\u2019engager au sein de la Fondation, ce sont ses actions de soutien \u00e0 la recherche, les valeurs qu\u2019elle incarne et les projets associatifs \u00e0 impact positif qu\u2019elle appuie dans les domaines environnementaux, soci\u00e9taux et sociaux. Cela m\u2019a donn\u00e9 envie d\u2019aller plus loin dans mon engagement au sein de la Fondation, \u00e0 travers la fonction de vice-pr\u00e9sident, avec pour ambition de conforter la Fondation dans sa strat\u00e9gie et de l\u2019appuyer dans sa mise en \u0153uvre.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e76d22f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e76d22f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-348ccc9\" data-id=\"348ccc9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12543c6 elementor-widget elementor-widget-text-editor\" data-id=\"12543c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>Quels ont \u00e9t\u00e9 les principaux accomplissements de la Fondation Grenoble INP au cours des derni\u00e8res ann\u00e9es ?<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8ff52d elementor-widget elementor-widget-text-editor\" data-id=\"a8ff52d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>NL :<\/strong> Nous avons pris une place dans le domaine de la recherche, avec la cr\u00e9ation des chaires d&rsquo;excellence. C\u2019est un d\u00e9fi qui n&rsquo;a jamais \u00e9t\u00e9 facile et qui reste complexe aujourd\u2019hui, dans un environnement assez foisonnant en termes d\u2019excellence et de recherche. Cela nous a permis de d\u00e9finir des th\u00e9matiques d&rsquo;excellence pertinentes et je suis particuli\u00e8rement fier de cette premi\u00e8re r\u00e9alisation. Le deuxi\u00e8me accomplissement r\u00e9side dans le nombre d&rsquo;\u00e9tudiants pour lesquels la Fondation a \u00e9t\u00e9 un v\u00e9ritable soutien, ouvrant de nouvelles opportunit\u00e9s dans leurs parcours. Cette aide a \u00e9t\u00e9 de grande qualit\u00e9 et elle a eu un impact significatif, en transformant leur vie de mani\u00e8re profonde.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1607a6 elementor-widget elementor-widget-text-editor\" data-id=\"f1607a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>LP :<\/strong> La Fondation joue un r\u00f4le de facilitateur dans l\u2019\u00e9mergence et l\u2019accompagnement de projets entre les entreprises et les diff\u00e9rents laboratoires de Grenoble INP. Elle remplit ce r\u00f4le \u00e0 travers une quinzaine de Chaires d\u2019excellence, qui embarquent de nombreuses th\u00e8ses sur des sujets ambitieux, et \u00e0 travers de nombreux partenariats industriels pluriannuels (plus de 300 depuis la cr\u00e9ation de la Fondation). De plus, la Fondation a d\u00e9velopp\u00e9, d\u00e8s sa cr\u00e9ation, une politique et un programme d\u2019actions afin de promouvoir l\u2019\u00e9galit\u00e9 des chances et la diversit\u00e9 au sein de Grenoble INP, avec notamment des bourses \u00e0 destination des \u00e9tudiants (presque un millier en 12 ans), des pr\u00eats d\u2019honneur, mais \u00e9galement le soutien d\u2019une centaine de projets associatifs porteurs de ces valeurs de solidarit\u00e9.\u00a0<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87eb525 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87eb525\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a4f54d\" data-id=\"8a4f54d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85562d1 elementor-widget elementor-widget-text-editor\" data-id=\"85562d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>Quels sont les domaines d\u2019innovation et de recherche prioritaires pour la Fondation et quel impact peut-elle avoir sur le monde de demain ?<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe2824 elementor-widget elementor-widget-text-editor\" data-id=\"4fe2824\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>LP :<\/strong> Les principaux domaines de recherche et d\u2019innovation dans lesquels la Fondation doit s\u2019investir et s\u2019investit d\u00e9j\u00e0 sont associ\u00e9s aux transitions et enjeux majeurs qui nous attendent : transitions \u00e9nerg\u00e9tique, environnementale, soci\u00e9tale, num\u00e9rique et industrielle, cette derni\u00e8re \u00e9tant au service des pr\u00e9c\u00e9dentes. Le spectre est large et nos ambitions sont toutes aussi grandes.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c60ca1c elementor-widget elementor-widget-text-editor\" data-id=\"c60ca1c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>NL :<\/strong> Nous aspirons \u00e0 donner aux ing\u00e9nieurs de demain une compr\u00e9hension solide des enjeux climatiques et environnementaux et \u00e0 les former pour qu\u2019ils soient capables de prendre des d\u00e9cisions \u00e9clair\u00e9es et responsables. Je suis convaincu que les nouvelles g\u00e9n\u00e9rations sont capables de prendre conscience de ces enjeux d\u2019agir en cons\u00e9quence. La Fondation Grenoble INP souhaite jouer un r\u00f4le cl\u00e9 pour fa\u00e7onner un monde plus durable, en proposant des actions concr\u00e8tes et porteuses de sens. Nous collaborons avec les \u00e9tudiants, les entreprises et l&rsquo;\u00e9cosyst\u00e8me de la recherche pour d\u00e9velopper des projets technologiques innovants et respectueux de l&rsquo;environnement. Nous croyons fermement que chaque individu, chaque \u00e9tudiant, chaque entreprise a un r\u00f4le \u00e0 jouer pour l\u2019avenir.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-281092a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"281092a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99c38f9\" data-id=\"99c38f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ffa9c1 elementor-widget elementor-widget-text-editor\" data-id=\"6ffa9c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>Quels sont les principaux enjeux auxquels la Fondation est confront\u00e9e ?<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d8d7ba elementor-widget elementor-widget-text-editor\" data-id=\"9d8d7ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>NL :<\/strong> Tout d&rsquo;abord, il y a la question de la notori\u00e9t\u00e9. Nous devons clarifier et faire conna\u00eetre nos actions, tout en distinguant clairement notre mission des autres initiatives de Grenoble INP. Ensuite, il y a l&rsquo;enjeu de la reconnaissance de l&rsquo;excellence de nos projets de recherche. Nous devons mieux promouvoir nos travaux et leurs retomb\u00e9es positives, en particulier aupr\u00e8s des acteurs de la recherche, des entreprises et des partenaires institutionnels. Le troisi\u00e8me enjeu est d&rsquo;ordre humain. Au c\u0153ur de la Fondation, il y a des individus avec des aspirations et des parcours uniques, \u00e0 qui nous devons offrir un soutien personnalis\u00e9 pour les aider dans leur d\u00e9veloppement personnel et professionnel. Enfin, le volet financier est un enjeu crucial. Pour r\u00e9aliser nos actions et cro\u00eetre, nous devons attirer de nouveaux donateurs, qu&rsquo;ils soient des entreprises ou des particuliers. Cela n\u00e9cessite la cr\u00e9ation d&rsquo;un fort sentiment d&rsquo;appartenance et faire en sorte que nos donateurs soient fiers de soutenir notre ambition.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51f9f0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51f9f0b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ef9715\" data-id=\"5ef9715\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1da91a elementor-widget elementor-widget-text-editor\" data-id=\"f1da91a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h2>Quelles sont vos perspectives et votre vision pour l&rsquo;avenir de la Fondation Grenoble INP ?<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7738b66 elementor-widget elementor-widget-text-editor\" data-id=\"7738b66\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>NL :<\/strong> Pour l\u2019ann\u00e9e 2024, souhaitons d\u00e9velopper davantage les th\u00e9matiques d&rsquo;excellence des Chaires pour toucher plus largement toutes les \u00e9coles de Grenoble INP. Bien s\u00fbr, nous continuerons \u00e0 soutenir un certain nombre d&rsquo;initiatives pour les \u00e9tudiants boursiers.<\/p><p>Pour ce qui est du long terme, je souhaite encourager les rencontres entre le monde de la recherche, de la formation et de l&rsquo;industrie. Ces trois piliers sont essentiels pour le d\u00e9veloppement de l&rsquo;excellence et ce triptyque doit mieux se conna\u00eetre et mieux \u00e9valuer ses besoins pour se d\u00e9velopper dans un monde qui a \u00e9volu\u00e9. De plus, je souhaite que les \u00e9tudiants puissent mieux comprendre la r\u00e9alit\u00e9 de l&rsquo;entreprise et les opportunit\u00e9s qu&rsquo;elle offre. Nous devons favoriser les \u00e9changes entre ces deux parties pour permettre aux jeunes de faire des choix \u00e9clair\u00e9s dans leur parcours professionnel. Je pense que nous avons tous un r\u00f4le crucial \u00e0 jouer dans la lutte contre le changement climatique et nous pouvons \u0153uvrer ensemble pour pr\u00e9server notre environnement et construire un avenir durable pour tous.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4918995 elementor-widget elementor-widget-text-editor\" data-id=\"4918995\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>LP :<\/strong> Nous avons la vision d\u2019un avenir radieux, car Grenoble INP et sa Fondation sont au c\u0153ur des enjeux &amp; transitions d\u00e9j\u00e0 en cours et qui vont s\u2019acc\u00e9l\u00e9rer. Et aussi parce que la Fondation est parfaitement positionn\u00e9e et en lien avec les \u00e9tudiants, les enseignants, les chercheurs, les \u00e9coles, les entreprises et les m\u00e9c\u00e8nes bien s\u00fbr !<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a27e711 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a27e711\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5822d6e\" data-id=\"5822d6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3189843 elementor-widget elementor-widget-spacer\" data-id=\"3189843\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ca5460 elementor-widget elementor-widget-text-editor\" data-id=\"7ca5460\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><em><strong><u>La Fondation Grenoble INP, inspirer par les sciences et le progr\u00e8s un monde durable<\/u><\/strong><\/em><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71f88de elementor-widget elementor-widget-text-editor\" data-id=\"71f88de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Depuis 2010, la Fondation Grenoble INP a pour mission de soutenir l\u2019ambition et le d\u00e9veloppement des 8 \u00e9coles, 39 laboratoires et 8300 \u00e9tudiants ing\u00e9nieurs managers que regroupe Grenoble INP, Institut d\u2019ing\u00e9nierie et de management de l\u2019Universit\u00e9 Grenoble Alpes. Soutenue par plus de 500 M\u00e9c\u00e8nes et Donateurs particuliers, la Fondation Grenoble INP r\u00e9unit les \u00e9tudiants, les enseignants-chercheurs et les entrepreneurs pour construire le monde de demain \u00e0 travers le d\u00e9veloppement de projets innovants et soci\u00e9taux pour faire rayonner l\u2019excellence acad\u00e9mique et scientifique is\u00e9roise jusqu\u2019\u00e0 l\u2019international.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1377304 elementor-widget elementor-widget-text-editor\" data-id=\"1377304\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>En chiffres\u00a0:<\/p><ul><li>+ de 15 M\u20ac de m\u00e9c\u00e9nat mobilis\u00e9s<\/li><li>3 programmes de m\u00e9c\u00e9nat d\u00e9velopp\u00e9s<\/li><li>14 chaires d\u2019excellence industrielle (recherche et d\u2019enseignement)<\/li><li>+ de 950 bourses distribu\u00e9es, 22 pr\u00eats d\u2019honneur, 124 projets associatifs et d\u2019\u00e9coles financ\u00e9s pour un montant de plus de 3 M\u20ac<\/li><\/ul>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-732dc9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"732dc9c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b47353b\" data-id=\"b47353b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df5d5b3 elementor-widget elementor-widget-spacer\" data-id=\"df5d5b3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d93bac elementor-widget elementor-widget-text-editor\" data-id=\"2d93bac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><a href=\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/2023-28-09-CP_CA_Fondation.docx\" target=\"_blank\" rel=\"noopener\"><strong><em>T\u00e9l\u00e9charger le Communiqu\u00e9 de Presse<\/em><\/strong><\/a><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.<\/p>","protected":false},"author":7,"featured_media":16555,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[475],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Conseil d&#039;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident. - Fondation Grenoble INP<\/title>\n<meta name=\"description\" content=\"Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondation-grenoble-inp.fr\/en\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Conseil d&#039;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident. - Fondation Grenoble INP\" \/>\n<meta property=\"og:description\" content=\"Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondation-grenoble-inp.fr\/en\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Grenoble INP\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-11T09:09:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T11:09:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Dubreuil\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\",\"name\":\"Fondation INP Grenoble\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"width\":512,\"height\":512,\"caption\":\"Fondation INP Grenoble\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"name\":\"Fondation Grenoble INP\",\"description\":\"#OsezlAvenir\",\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png\",\"width\":\"795\",\"height\":\"483\",\"caption\":\"Nicolas Leterrier et Laurent Perotin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#webpage\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/\",\"name\":\"Le Conseil d'Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident. - Fondation Grenoble INP\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#primaryimage\"},\"datePublished\":\"2023-10-11T09:09:03+00:00\",\"dateModified\":\"2023-10-30T11:09:18+00:00\",\"description\":\"Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.\",\"breadcrumb\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fondation-grenoble-inp.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Conseil d&rsquo;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident.\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94\"},\"headline\":\"Le Conseil d&rsquo;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident.\",\"datePublished\":\"2023-10-11T09:09:03+00:00\",\"dateModified\":\"2023-10-30T11:09:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#webpage\"},\"wordCount\":1494,\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png\",\"articleSection\":[\"La Fondation\"],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94\",\"name\":\"Marie Dubreuil\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g\",\"caption\":\"Marie Dubreuil\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Conseil d'Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident. - Fondation Grenoble INP","description":"Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondation-grenoble-inp.fr\/en\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/","og_locale":"en_US","og_type":"article","og_title":"Le Conseil d'Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident. - Fondation Grenoble INP","og_description":"Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.","og_url":"https:\/\/fondation-grenoble-inp.fr\/en\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/","og_site_name":"Fondation Grenoble INP","article_published_time":"2023-10-11T09:09:03+00:00","article_modified_time":"2023-10-30T11:09:18+00:00","og_image":[{"width":"795","height":"483","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marie Dubreuil","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fondation-grenoble-inp.fr\/#organization","name":"Fondation INP Grenoble","url":"https:\/\/fondation-grenoble-inp.fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#logo","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","width":512,"height":512,"caption":"Fondation INP Grenoble"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/fondation-grenoble-inp.fr\/#website","url":"https:\/\/fondation-grenoble-inp.fr\/","name":"Fondation Grenoble INP","description":"#OsezlAvenir","publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#primaryimage","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png","width":"795","height":"483","caption":"Nicolas Leterrier et Laurent Perotin"},{"@type":"WebPage","@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#webpage","url":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/","name":"Le Conseil d'Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident. - Fondation Grenoble INP","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#primaryimage"},"datePublished":"2023-10-11T09:09:03+00:00","dateModified":"2023-10-30T11:09:18+00:00","description":"Nicolas Leterrier a \u00e9t\u00e9 reconduit dans sa fonction de Pr\u00e9sident de la Fondation, Laurent Perotin a quant \u00e0 lui pris le relais de Gilles Feuillade en tant que vice-pr\u00e9sident.","breadcrumb":{"@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fondation-grenoble-inp.fr\/"},{"@type":"ListItem","position":2,"name":"Le Conseil d&rsquo;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident."}]},{"@type":"Article","@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#article","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#webpage"},"author":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94"},"headline":"Le Conseil d&rsquo;Administration de la Fondation Grenoble INP a reconduit Nicolas Leterrier \u00e0 la pr\u00e9sidence et nomme Laurent Perotin vice-pr\u00e9sident.","datePublished":"2023-10-11T09:09:03+00:00","dateModified":"2023-10-30T11:09:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#webpage"},"wordCount":1494,"publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/le-conseil-dadministration-de-la-fondation-grenoble-inp-a-reconduit-nicolas-leterrier-a-la-presidence-et-nomme-laurent-perotin-vice-president\/#primaryimage"},"thumbnailUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2023\/10\/Nicolas-Leterrier-x-Laurent-Perotin.png","articleSection":["La Fondation"],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/7c36548ebaddf05ba7a055d161ebff94","name":"Marie Dubreuil","image":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358eb0ab274d9479ce7c23b8a3f0a360?s=96&d=mm&r=g","caption":"Marie Dubreuil"}}]}},"_links":{"self":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/16554"}],"collection":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/comments?post=16554"}],"version-history":[{"count":14,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/16554\/revisions"}],"predecessor-version":[{"id":16751,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/16554\/revisions\/16751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media\/16555"}],"wp:attachment":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media?parent=16554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/categories?post=16554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/tags?post=16554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}