{"id":8716,"date":"2016-12-07T13:37:16","date_gmt":"2016-12-07T12:37:16","guid":{"rendered":"https:\/\/fondation-grenoble-inp.fr2016\/12\/07\/https-fondation-grenoble-inp-fr-breye-innovation-de-lyceens-profit-malvoyants\/"},"modified":"2023-07-24T15:08:16","modified_gmt":"2023-07-24T13:08:16","slug":"breye-innovation-de-lyceens-profit-malvoyants","status":"publish","type":"post","link":"https:\/\/fondation-grenoble-inp.fr\/en\/breye-innovation-de-lyceens-profit-malvoyants\/","title":{"rendered":"Breye, une innovation de lyc\u00e9ens au profit des malvoyants"},"content":{"rendered":"<h2><strong>Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille qui a re\u00e7u lors de la finale des Olympiades de Sciences de l\u2019Ing\u00e9nieur, en mai dernier, le prix de la cr\u00e9ation solidaire pour leur projet Breye<\/strong>.<\/h2>\n<p>Le projet Breye est n\u00e9 du constat que dans la vie quotidienne d&rsquo;un malvoyant l&rsquo;acc\u00e8s \u00e0 l&rsquo;information est restreint. Livres, SMS, po\u00e8mes, menu, tout texte dactylographi\u00e9 n&rsquo;est pas rendu accessible. Ainsi, les \u00e9l\u00e8ves du <a href=\"http:\/\/ernest-couteaux-saint-amand-les-eaux.savoirsnumeriques5962.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lyc\u00e9e Ernest Couteaux<\/a>, accompagn\u00e9s par leurs professeurs ont cherch\u00e9 \u00e0 r\u00e9soudre ce probl\u00e8me. Ils ont \u00e9galement travaill\u00e9 sur ce projet avec Clarisse, une personne aveugle.<\/p>\n<p>Leur syst\u00e8me, sous forme de souris, est connect\u00e9 \u00e0 une application pour smartphone adapt\u00e9e aux malvoyants. Il permet de convertir tout texte dactylographi\u00e9 ou num\u00e9rique en braille (le braille \u00e9tant une \u00e9criture en relief adapt\u00e9e pour personne aveugle).<\/p>\n<p>Plusieurs fonctionnalit\u00e9s sont disponibles sur leur application comme lire un SMS, ou encore lire tous textes en le scannant avec le smartphone.<\/p>\n<p>Enfin ils ont \u00e9galement travaill\u00e9 sur un mode \u00e9ducatif, permettant d&rsquo;apprendre le braille \u00e0 son rythme.<\/p>\n<p>Chaque lettre en braille est compos\u00e9e d&rsquo;une combinaison de 6 points, et est cr\u00e9\u00e9e au moyen de servomoteurs, soulevant des pics dans la souris.<\/p>\n<p>Aujourd\u2019hui, ils ont des perspectives de d\u00e9veloppement avec l&rsquo;id\u00e9e de miniaturiser leur syst\u00e8me dans une coque de t\u00e9l\u00e9phone. Cependant en tant que lyc\u00e9en ils n\u2019ont pas encore les capacit\u00e9s de mener \u00e0 bien cette \u00e9volution de BREYE.<\/p>\n<h3><strong>L\u2019\u00e9quipe du Lyc\u00e9e Ernest Couteaux de Saint-Amand-des-Eaux (59)\u00a0: <\/strong><\/h3>\n<ul>\n<li>Louis Kasemierczak<\/li>\n<li>Florian Guislain<\/li>\n<li>L\u00e9o Lylak<\/li>\n<li>Victor Igla<\/li>\n<li>Tristan N\u00e8ve<\/li>\n<li>Robinson Bloquel<\/li>\n<li>Matthieu Desfontaines<\/li>\n<\/ul>\n<ul>\n<li>Mr Mathon<\/li>\n<li>Mr Morel<\/li>\n<li>Mr Watte<\/li>\n<\/ul>\n<p>Contact\u00a0: <a href=\"http:\/\/breye@netcourrier.com\" target=\"_blank\" rel=\"noopener noreferrer\">breye@netcourrier.com<\/a><\/p>\n<p><a href=\"http:\/\/dev.fondation-grenoble-inp.fr\/wp-content\/uploads\/2017\/11\/Diapo-souris-Breye.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Pr\u00e9sentation de la souis Breye<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille qui a re\u00e7u lors de la finale des Olympiades de Sciences de l\u2019Ing\u00e9nieur, en mai dernier, le prix de la cr\u00e9ation solidaire pour leur projet Breye. Le [&hellip;]<\/p>","protected":false},"author":4,"featured_media":6835,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[478],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Breye: Une innovation au profit des malvoyants - Fondation Grenoble INP<\/title>\n<meta name=\"description\" content=\"Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondation-grenoble-inp.fr\/en\/breye-innovation-de-lyceens-profit-malvoyants\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breye: Une innovation au profit des malvoyants - Fondation Grenoble INP\" \/>\n<meta property=\"og:description\" content=\"Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondation-grenoble-inp.fr\/en\/breye-innovation-de-lyceens-profit-malvoyants\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Grenoble INP\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-07T12:37:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T13:08:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Murielle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\",\"name\":\"Fondation INP Grenoble\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"width\":512,\"height\":512,\"caption\":\"Fondation INP Grenoble\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"name\":\"Fondation Grenoble INP\",\"description\":\"#OsezlAvenir\",\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg\",\"width\":\"980\",\"height\":\"653\",\"caption\":\"Fondation_Grenoble_INP_GALA_2016-0111\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#webpage\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/\",\"name\":\"Breye: Une innovation au profit des malvoyants - Fondation Grenoble INP\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#primaryimage\"},\"datePublished\":\"2016-12-07T12:37:16+00:00\",\"dateModified\":\"2023-07-24T13:08:16+00:00\",\"description\":\"Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille\",\"breadcrumb\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fondation-grenoble-inp.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Breye, une innovation de lyc\u00e9ens au profit des malvoyants\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf\"},\"headline\":\"Breye, une innovation de lyc\u00e9ens au profit des malvoyants\",\"datePublished\":\"2016-12-07T12:37:16+00:00\",\"dateModified\":\"2023-07-24T13:08:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#webpage\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg\",\"articleSection\":[\"Nous soutenons\"],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf\",\"name\":\"Murielle\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g\",\"caption\":\"Murielle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breye: Une innovation au profit des malvoyants - Fondation Grenoble INP","description":"Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondation-grenoble-inp.fr\/en\/breye-innovation-de-lyceens-profit-malvoyants\/","og_locale":"en_US","og_type":"article","og_title":"Breye: Une innovation au profit des malvoyants - Fondation Grenoble INP","og_description":"Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille","og_url":"https:\/\/fondation-grenoble-inp.fr\/en\/breye-innovation-de-lyceens-profit-malvoyants\/","og_site_name":"Fondation Grenoble INP","article_published_time":"2016-12-07T12:37:16+00:00","article_modified_time":"2023-07-24T13:08:16+00:00","og_image":[{"width":"980","height":"653","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Murielle","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fondation-grenoble-inp.fr\/#organization","name":"Fondation INP Grenoble","url":"https:\/\/fondation-grenoble-inp.fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#logo","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","width":512,"height":512,"caption":"Fondation INP Grenoble"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/fondation-grenoble-inp.fr\/#website","url":"https:\/\/fondation-grenoble-inp.fr\/","name":"Fondation Grenoble INP","description":"#OsezlAvenir","publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#primaryimage","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg","width":"980","height":"653","caption":"Fondation_Grenoble_INP_GALA_2016-0111"},{"@type":"WebPage","@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#webpage","url":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/","name":"Breye: Une innovation au profit des malvoyants - Fondation Grenoble INP","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#primaryimage"},"datePublished":"2016-12-07T12:37:16+00:00","dateModified":"2023-07-24T13:08:16+00:00","description":"Mardi 6 d\u00e9cembre, lors de la soir\u00e9e annuelle de la Fondation Grenoble INP, les \u00e9l\u00e8ves et professeurs du Lyc\u00e9e Ernest Couteaux ont pr\u00e9sent\u00e9s aux invit\u00e9s leur souris braille","breadcrumb":{"@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fondation-grenoble-inp.fr\/"},{"@type":"ListItem","position":2,"name":"Breye, une innovation de lyc\u00e9ens au profit des malvoyants"}]},{"@type":"Article","@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#article","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#webpage"},"author":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf"},"headline":"Breye, une innovation de lyc\u00e9ens au profit des malvoyants","datePublished":"2016-12-07T12:37:16+00:00","dateModified":"2023-07-24T13:08:16+00:00","mainEntityOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#webpage"},"wordCount":328,"publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/breye-innovation-de-lyceens-profit-malvoyants\/#primaryimage"},"thumbnailUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Fondation_Grenoble_INP_GALA_2016-0111.jpg","articleSection":["Nous soutenons"],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf","name":"Murielle","image":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g","caption":"Murielle"}}]}},"_links":{"self":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8716"}],"collection":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/comments?post=8716"}],"version-history":[{"count":1,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8716\/revisions"}],"predecessor-version":[{"id":10803,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8716\/revisions\/10803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media\/6835"}],"wp:attachment":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media?parent=8716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/categories?post=8716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/tags?post=8716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}