{"id":8743,"date":"2017-11-13T11:02:22","date_gmt":"2017-11-13T10:02:22","guid":{"rendered":"https:\/\/fondation-grenoble-inp.fr2017\/11\/13\/https-fondation-grenoble-inp-fr-ecologie-acoustique-marine\/"},"modified":"2023-07-24T15:07:55","modified_gmt":"2023-07-24T13:07:55","slug":"ecologie-acoustique-marine","status":"publish","type":"post","link":"https:\/\/fondation-grenoble-inp.fr\/en\/ecologie-acoustique-marine\/","title":{"rendered":"\u00ab\u00a0Ecologie &#038; Acoustique sous-marine\u00a0\u00bb"},"content":{"rendered":"<h2>Le 13 &amp; 14 novembre 2017, \u00e0 Phelma Minatec, la Chaire Chorus et l&rsquo;Agence de l&rsquo;Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab\u00a0l\u2019\u00e9cologie et l\u2019acoustique sous-marine\u00a0\u00bb.<\/h2>\n<p>Au programme de ces deux jours :<\/p>\n<h3>Lundi 13 novembre : S\u00e9ance d&rsquo;\u00e9coacoustique<\/h3>\n<ul>\n<li>10h40 : Communication acoustique chez les poissons, par Clara Amorim de ISPA Istituto Universitario, Lisbonne<\/li>\n<li>11h20 : Acoustique et diversit\u00e9\n<ul>\n<li>Communaut\u00e9s de poissons acoustiques: La diversit\u00e9 sonore des habitats rocheux refl\u00e8te la diversit\u00e9 des esp\u00e8ces et au-del\u00e0, par Elena Desider\u00e0 de l&rsquo;Universit\u00e9 de Nice &amp; Universit\u00e0 di Padova &amp; CHORUS<\/li>\n<li>Complexit\u00e9 acoustique des communaut\u00e9s vocales de poissons: un champ et une validation contr\u00f4l\u00e9e, par Marta Bolgan de l&rsquo;Universit\u00e9 de Li\u00e8ge<\/li>\n<\/ul>\n<\/li>\n<li>13h40 : Acoustique et post-larves\n<ul>\n<li>Richesse sonore et peuplement post-larvaire, par Lucia Di Iorio de la Chaire Chorus<\/li>\n<li>SEANAPS: \u00c9valuation du profil du paysage sonore de l&rsquo;offshore \u00e0 l&rsquo;int\u00e9rieur du port, par Julie Lossent de la Chaire Chorus &amp; Anais Gudefin d&rsquo;Ecocean<\/li>\n<\/ul>\n<\/li>\n<li>15h30 : l&rsquo;acoustique des algues\n<ul>\n<li>La biophonie de l&rsquo;herbier de la Revellata Calvi, par C\u00e9dric Gervaise de la Chaire Chorus<\/li>\n<li>le \u00ab\u00a0kwa\u00a0\u00bb, indicateur potentiel du son de poisson ?, par Lucia Di Iorio, de la Chaire Chorus<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>Mardi 14 novembre : Les observatoires acoustiques passifs<\/h3>\n<ul>\n<li>9h00 : MSFD, Descripteur 11 de la MFSD : impl\u00e9mentations en Eurpe et en France, situation en 2017 et perspectives, par Bazile Kinda de SHOM<\/li>\n<li>9h30 : Les observatoires, \u00c9tat de l&rsquo;art des observatoires c\u00e2bl\u00e9s et des objets connect\u00e9s sous-marins par Didier Clec&rsquo;h &amp; Laurent Dufrechou de RTSYS<\/li>\n<li>10h10 : Le r\u00e9seau CALME a trois ans: premiers r\u00e9sultats et retours par C\u00e9dric Gervaise de la Chaire Chorus<\/li>\n<li>10h40 : Acoustique active et \u00e9cologie, \u00c9tat de l&rsquo;art de l&rsquo;\u00e9valuation de l&rsquo;\u00e9tat \u00e9cologique des habitats c\u00f4tiers avec plongeurs et m\u00e9thodes acoustiques actives par Claire Noel de Semantic TS<\/li>\n<li>13h00 : fin du s\u00e9minaire<\/li>\n<\/ul>\n<h3>A propos de la chaire Chorus<\/h3>\n<p>CHORUS r\u00e9alise au sein de la Fondation Partenariale Grenoble INP un programme de recherches multidisciplinaires (sciences de l\u2019ing\u00e9nieur et de l\u2019environnement) cr\u00e9\u00e9 et anim\u00e9 par Lucia Di Iorio et C\u00e9dric Gervaise. Dans leur activit\u00e9 de recherche, ils utilisent les paysages acoustiques comme proxy environnemental pour \u00e9tudier la structure, le fonctionnement, l\u2019\u00e9tat et la dynamique des \u00e9cosyst\u00e8mes marins.<\/p>\n<p><a href=\"https:\/\/fondation-grenoble-inp.fr\/en\/nos-actions\/contribuer-developpement-recherche\/chaire-chorus\/\" target=\"_blank\" rel=\"noopener noreferrer\">En savoir plus<\/a><\/p>\n<h3>A propos de l&rsquo;Agence de l&rsquo;Eau RMC<\/h3>\n<div class=\"blocContenu\">\n<div id=\"c67\" class=\"csc-default\">\n<p class=\"bodytext\">Cr\u00e9\u00e9e par la loi sur l\u2019eau de 1964, l\u2019agence de l\u2019eau est un \u00e9tablissement public de l\u2019\u00c9tat, sous la tutelle du\u00a0minist\u00e8re de l\u2019environnement. Elle\u00a0a pour missions de contribuer \u00e0 am\u00e9liorer la gestion de l\u2019eau, de lutter contre sa pollution et de prot\u00e9ger les milieux aquatiques.<\/p>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/www.eaurmc.fr\/index.php?qui-sommes-nous\" target=\"_blank\" rel=\"noopener noreferrer\">En savoir plus<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 13 &amp; 14 novembre 2017, \u00e0 Phelma Minatec, la Chaire Chorus et l&rsquo;Agence de l&rsquo;Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab\u00a0l\u2019\u00e9cologie et l\u2019acoustique sous-marine\u00a0\u00bb. Au programme de ces deux jours : Lundi 13 novembre : S\u00e9ance d&rsquo;\u00e9coacoustique 10h40 : Communication acoustique chez les poissons, par Clara Amorim de ISPA Istituto Universitario, [&hellip;]<\/p>","protected":false},"author":4,"featured_media":6847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[476],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ecologie &amp; Acoustique sous-marine - Fondation Grenoble INP<\/title>\n<meta name=\"description\" content=\"Minatec, la Chaire Chorus et l\u2019Agence de l\u2019Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab l\u2019\u00e9cologie et l\u2019acoustique sous-marine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondation-grenoble-inp.fr\/en\/ecologie-acoustique-marine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecologie &amp; Acoustique sous-marine - Fondation Grenoble INP\" \/>\n<meta property=\"og:description\" content=\"Minatec, la Chaire Chorus et l\u2019Agence de l\u2019Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab l\u2019\u00e9cologie et l\u2019acoustique sous-marine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondation-grenoble-inp.fr\/en\/ecologie-acoustique-marine\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Grenoble INP\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-13T10:02:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T13:07:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Murielle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\",\"name\":\"Fondation INP Grenoble\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"width\":512,\"height\":512,\"caption\":\"Fondation INP Grenoble\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"name\":\"Fondation Grenoble INP\",\"description\":\"#OsezlAvenir\",\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg\",\"width\":\"1000\",\"height\":\"410\",\"caption\":\"Conf\u00e9rence2\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#webpage\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/\",\"name\":\"Ecologie & Acoustique sous-marine - Fondation Grenoble INP\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#primaryimage\"},\"datePublished\":\"2017-11-13T10:02:22+00:00\",\"dateModified\":\"2023-07-24T13:07:55+00:00\",\"description\":\"Minatec, la Chaire Chorus et l\u2019Agence de l\u2019Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab l\u2019\u00e9cologie et l\u2019acoustique sous-marine.\",\"breadcrumb\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fondation-grenoble-inp.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Ecologie &#038; Acoustique sous-marine\u00a0\u00bb\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf\"},\"headline\":\"\u00ab\u00a0Ecologie &#038; Acoustique sous-marine\u00a0\u00bb\",\"datePublished\":\"2017-11-13T10:02:22+00:00\",\"dateModified\":\"2023-07-24T13:07:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#webpage\"},\"wordCount\":448,\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg\",\"articleSection\":[\"Les Chaires\"],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf\",\"name\":\"Murielle\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g\",\"caption\":\"Murielle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecologie & Acoustique sous-marine - Fondation Grenoble INP","description":"Minatec, la Chaire Chorus et l\u2019Agence de l\u2019Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab l\u2019\u00e9cologie et l\u2019acoustique sous-marine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondation-grenoble-inp.fr\/en\/ecologie-acoustique-marine\/","og_locale":"en_US","og_type":"article","og_title":"Ecologie & Acoustique sous-marine - Fondation Grenoble INP","og_description":"Minatec, la Chaire Chorus et l\u2019Agence de l\u2019Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab l\u2019\u00e9cologie et l\u2019acoustique sous-marine.","og_url":"https:\/\/fondation-grenoble-inp.fr\/en\/ecologie-acoustique-marine\/","og_site_name":"Fondation Grenoble INP","article_published_time":"2017-11-13T10:02:22+00:00","article_modified_time":"2023-07-24T13:07:55+00:00","og_image":[{"width":"1000","height":"410","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Murielle","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fondation-grenoble-inp.fr\/#organization","name":"Fondation INP Grenoble","url":"https:\/\/fondation-grenoble-inp.fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#logo","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","width":512,"height":512,"caption":"Fondation INP Grenoble"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/fondation-grenoble-inp.fr\/#website","url":"https:\/\/fondation-grenoble-inp.fr\/","name":"Fondation Grenoble INP","description":"#OsezlAvenir","publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#primaryimage","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg","width":"1000","height":"410","caption":"Conf\u00e9rence2"},{"@type":"WebPage","@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#webpage","url":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/","name":"Ecologie & Acoustique sous-marine - Fondation Grenoble INP","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#primaryimage"},"datePublished":"2017-11-13T10:02:22+00:00","dateModified":"2023-07-24T13:07:55+00:00","description":"Minatec, la Chaire Chorus et l\u2019Agence de l\u2019Eau RMC organisent un s\u00e9minaire sur le th\u00e8me de \u00ab l\u2019\u00e9cologie et l\u2019acoustique sous-marine.","breadcrumb":{"@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fondation-grenoble-inp.fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Ecologie &#038; Acoustique sous-marine\u00a0\u00bb"}]},{"@type":"Article","@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#article","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#webpage"},"author":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf"},"headline":"\u00ab\u00a0Ecologie &#038; Acoustique sous-marine\u00a0\u00bb","datePublished":"2017-11-13T10:02:22+00:00","dateModified":"2023-07-24T13:07:55+00:00","mainEntityOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#webpage"},"wordCount":448,"publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/ecologie-acoustique-marine\/#primaryimage"},"thumbnailUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/Conference2.jpg","articleSection":["Les Chaires"],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf","name":"Murielle","image":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g","caption":"Murielle"}}]}},"_links":{"self":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8743"}],"collection":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/comments?post=8743"}],"version-history":[{"count":1,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8743\/revisions"}],"predecessor-version":[{"id":9901,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8743\/revisions\/9901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media\/6847"}],"wp:attachment":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media?parent=8743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/categories?post=8743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/tags?post=8743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}