{"id":8787,"date":"2020-05-04T12:42:21","date_gmt":"2020-05-04T10:42:21","guid":{"rendered":"https:\/\/fondation-grenoble-inp.fr2020\/05\/04\/https-fondation-grenoble-inp-fr-la-chaire-hope-lance-le-prix-hope-etudiant-2020\/"},"modified":"2023-07-24T15:06:26","modified_gmt":"2023-07-24T13:06:26","slug":"la-chaire-hope-lance-le-prix-hope-etudiant-2020","status":"publish","type":"post","link":"https:\/\/fondation-grenoble-inp.fr\/en\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/","title":{"rendered":"La Chaire HOPE lance le Prix HOPE Etudiant 2020"},"content":{"rendered":"<h2>La Chaire HOPE de la Fondation Grenoble INP lance le Prix HOPE Etudiant 2020. Il s\u2019agit d\u2019 un appel \u00e0 projet \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb pour accompagner les \u00e9tudiants de Grenoble INP, Institut d\u2019Ing\u00e9nierie et de Management et leurs pairs des autres Universit\u00e9s de France, qui souhaitent exp\u00e9rimenter un concept innovant au service de la lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique.<\/h2>\n<h3>Qu\u2019est-ce que la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique\u00a0?<\/h3>\n<ul>\n<li>La pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique d\u00e9signe l&rsquo;\u00e9tat de personnes n\u2019ayant pas un acc\u00e8s normal et r\u00e9gulier dans leur lieu de vie aux sources d&rsquo;\u00e9nergie n\u00e9cessaires \u00e0 la satisfaction de leurs besoins \u00e9l\u00e9mentaires (respirer, boire, manger, \u00e9liminer, se prot\u00e9ger du froid et de la chaleur, \u00eatre en s\u00e9curit\u00e9, dormir, se d\u00e9placer)<\/li>\n<li>En France, on estime \u00e0 12 Millions le nombre d\u2019individus concern\u00e9s par ce ph\u00e9nom\u00e8ne \u2013 (INSEE 2013)<\/li>\n<\/ul>\n<h3>Quels types de projets sont \u00e9ligibles au Prix HOPE Etudiant 2020 ?<\/h3>\n<p>Nous cherchons \u00e0 identifier\u00a0:<\/p>\n<ul>\n<li>Des id\u00e9es de projet qui puissent \u00eatre exp\u00e9riment\u00e9s sur l\u2019ann\u00e9e 2020-2021<\/li>\n<li>L\u2019id\u00e9e doit pr\u00e9senter un caract\u00e8re innovant soit dans sa nature soit dans son impl\u00e9mentation g\u00e9ographique ( essaimage)<\/li>\n<li>L\u2019id\u00e9e doit r\u00e9pondre \u00e0 un des th\u00e8mes de l\u2019ann\u00e9e<\/li>\n<\/ul>\n<h3>Th\u00e8mes 2020<\/h3>\n<p>Les th\u00e8mes 2020 ont \u00e9t\u00e9 d\u00e9finis par les 30 \u00e9tudiants qui ont particip\u00e9 au s\u00e9minaire \u00ab Repenser l\u2019Energie Ensemble \u00bb organis\u00e9 le 19 Mars 2020 par la Chaire HOPE et les chercheurs du projet ADEME RESILITERRE. Ces \u00e9tudiants d\u00e9j\u00e0 mobilis\u00e9s sur le th\u00e8me de la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique dans le cadre de leur cursus universitaire ou porteurs de projets b\u00e9n\u00e9voles ont estim\u00e9 prioritaires les th\u00e8mes suivants :<\/p>\n<ul>\n<li>Communication grand public\u00a0: lever le tabou sur le th\u00e8me de la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique pour susciter l\u2019action<\/li>\n<li>Guichet unique pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique<\/li>\n<li>Chantiers participatifs, auto-r\u00e9habilitation accompagn\u00e9e<\/li>\n<li>Mieux articuler les diff\u00e9rentes \u00e9chelles d&rsquo;actions (nationale, d\u00e9partementale, intercommunale, communale, public, priv\u00e9, association, b\u00e9n\u00e9volat)<\/li>\n<li>Faire une proposition de loi ( lien vers la <a href=\"https:\/\/www.senat.fr\/fileadmin\/Fichiers\/Images\/relations_internationales\/Cooperation_interparlementaire\/Guides_et_recueils\/Rediger_la_loi_juin_2007.pdf\">m\u00e9thodologie<\/a> )<\/li>\n<\/ul>\n<h3>Qui peut r\u00e9pondre ?<\/h3>\n<ul>\n<li>Groupe de minimum deux \u00e9tudiants (si vous \u00eates seul, vous pouvez constituer votre \u00e9quipe en rejoignant le groupe Facebook <a href=\"https:\/\/www.facebook.com\/groups\/2733375720056350\/\">HOPE Etudiant<\/a>)<\/li>\n<li>Il est fortement recommand\u00e9 que les \u00e9quipes d\u2019\u00e9tudiants repr\u00e9sentent au moins deux \u00e9coles diff\u00e9rentes<\/li>\n<li>Il est n\u00e9cessaire d\u2019\u00eatre disponible en 2020-2021 pour un suivi mensuel du projet<\/li>\n<\/ul>\n<h3>Proc\u00e9dure pour candidater<\/h3>\n<ul>\n<li>Envoyer son id\u00e9e de projet ( le concept, le th\u00e8me choisi, en quoi est-ce innovant, public cible, l\u2019\u00e9quipe, business plan, le planning etc..) en remplissant le <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfgyNSXIQ8Bxw5W98ru1232j6rO3wT6fF-Ze8xWa_UbvKxKag\/viewform\" target=\"_blank\" rel=\"noopener noreferrer\">formulaire de candidature<\/a> au Prix HOPE Etudiant 2020<\/li>\n<li>Se tenir \u00e0 la disposition de la Chaire HOPE pour tout compl\u00e9ment sur le dossier<\/li>\n<\/ul>\n<h3>Modalit\u00e9 de d\u00e9p\u00f4t du projet<\/h3>\n<ul>\n<li>Date limite de d\u00e9p\u00f4t des dossiers : 15 d\u00e9cembre 2020<\/li>\n<\/ul>\n<h3>Le Prix 2020<\/h3>\n<ul>\n<li>L\u2019\u00e9quipe qui remportera le Prix HOPE ETUDIANT 2020 se verra offrir un voyage de deux jours organis\u00e9 par la Chaire HOPE avec au moins une immersion aupr\u00e8s d\u2019un organisme qui fait r\u00e9f\u00e9rence dans la lutte contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique et une rencontre avec une personnalit\u00e9 qui fait r\u00e9f\u00e9rence \u00e0 l\u2019\u00e9chelon national sur le th\u00e8me choisi.<\/li>\n<li>La Chaire HOPE r\u00e9compensera les finalistes par une ann\u00e9e de coaching en management de projet et la mise en relation avec le r\u00e9seau des experts nationaux de la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La Chaire HOPE de la Fondation Grenoble INP lance le Prix HOPE Etudiant 2020. Il s\u2019agit d\u2019 un appel \u00e0 projet \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb pour accompagner les \u00e9tudiants de Grenoble INP, Institut d\u2019Ing\u00e9nierie et de Management et leurs pairs des autres Universit\u00e9s [&hellip;]<\/p>","protected":false},"author":4,"featured_media":6962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[476],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Chaire HOPE lance le Prix HOPE Etudiant 2020<\/title>\n<meta name=\"description\" content=\"La Chaire HOPE lance le Prix HOPE Etudiant 2020 \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondation-grenoble-inp.fr\/en\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Chaire HOPE lance le Prix HOPE Etudiant 2020\" \/>\n<meta property=\"og:description\" content=\"La Chaire HOPE lance le Prix HOPE Etudiant 2020 \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondation-grenoble-inp.fr\/en\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Grenoble INP\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-04T10:42:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T13:06:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Murielle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\",\"name\":\"Fondation INP Grenoble\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png\",\"width\":512,\"height\":512,\"caption\":\"Fondation INP Grenoble\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/\",\"name\":\"Fondation Grenoble INP\",\"description\":\"#OsezlAvenir\",\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg\",\"contentUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg\",\"width\":\"1200\",\"height\":\"493\",\"caption\":\"Young business people are discussing together a new startup project. A glowing light bulb as a new idea.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#webpage\",\"url\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/\",\"name\":\"La Chaire HOPE lance le Prix HOPE Etudiant 2020\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#primaryimage\"},\"datePublished\":\"2020-05-04T10:42:21+00:00\",\"dateModified\":\"2023-07-24T13:06:26+00:00\",\"description\":\"La Chaire HOPE lance le Prix HOPE Etudiant 2020 \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb\",\"breadcrumb\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fondation-grenoble-inp.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Chaire HOPE lance le Prix HOPE Etudiant 2020\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf\"},\"headline\":\"La Chaire HOPE lance le Prix HOPE Etudiant 2020\",\"datePublished\":\"2020-05-04T10:42:21+00:00\",\"dateModified\":\"2023-07-24T13:06:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#webpage\"},\"wordCount\":597,\"publisher\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg\",\"articleSection\":[\"Les Chaires\"],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf\",\"name\":\"Murielle\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fondation-grenoble-inp.fr\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g\",\"caption\":\"Murielle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Chaire HOPE lance le Prix HOPE Etudiant 2020","description":"La Chaire HOPE lance le Prix HOPE Etudiant 2020 \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondation-grenoble-inp.fr\/en\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/","og_locale":"en_US","og_type":"article","og_title":"La Chaire HOPE lance le Prix HOPE Etudiant 2020","og_description":"La Chaire HOPE lance le Prix HOPE Etudiant 2020 \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb","og_url":"https:\/\/fondation-grenoble-inp.fr\/en\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/","og_site_name":"Fondation Grenoble INP","article_published_time":"2020-05-04T10:42:21+00:00","article_modified_time":"2023-07-24T13:06:26+00:00","og_image":[{"width":"1200","height":"493","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Murielle","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fondation-grenoble-inp.fr\/#organization","name":"Fondation INP Grenoble","url":"https:\/\/fondation-grenoble-inp.fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#logo","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-fondation-inp-grenoble.png","width":512,"height":512,"caption":"Fondation INP Grenoble"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/fondation-grenoble-inp.fr\/#website","url":"https:\/\/fondation-grenoble-inp.fr\/","name":"Fondation Grenoble INP","description":"#OsezlAvenir","publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondation-grenoble-inp.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#primaryimage","inLanguage":"en-US","url":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg","contentUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg","width":"1200","height":"493","caption":"Young business people are discussing together a new startup project. A glowing light bulb as a new idea."},{"@type":"WebPage","@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#webpage","url":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/","name":"La Chaire HOPE lance le Prix HOPE Etudiant 2020","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#primaryimage"},"datePublished":"2020-05-04T10:42:21+00:00","dateModified":"2023-07-24T13:06:26+00:00","description":"La Chaire HOPE lance le Prix HOPE Etudiant 2020 \u00ab Etudiants en Action pour Innover au Service de la Lutte contre la Pr\u00e9carit\u00e9 Energ\u00e9tique \u00bb","breadcrumb":{"@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fondation-grenoble-inp.fr\/"},{"@type":"ListItem","position":2,"name":"La Chaire HOPE lance le Prix HOPE Etudiant 2020"}]},{"@type":"Article","@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#article","isPartOf":{"@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#webpage"},"author":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf"},"headline":"La Chaire HOPE lance le Prix HOPE Etudiant 2020","datePublished":"2020-05-04T10:42:21+00:00","dateModified":"2023-07-24T13:06:26+00:00","mainEntityOfPage":{"@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#webpage"},"wordCount":597,"publisher":{"@id":"https:\/\/fondation-grenoble-inp.fr\/#organization"},"image":{"@id":"https:\/\/fondation-grenoble-inp.fr\/la-chaire-hope-lance-le-prix-hope-etudiant-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/fondation-grenoble-inp.fr\/wp-content\/uploads\/2020\/09\/HOPE_Precarite-energetiqueSlider-e1581586200354.jpeg","articleSection":["Les Chaires"],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/fondation-grenoble-inp.fr\/#\/schema\/person\/b3b57bf0f0ccfd32237a6d2dbbe56adf","name":"Murielle","image":{"@type":"ImageObject","@id":"https:\/\/fondation-grenoble-inp.fr\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/369007e9cd71fa50966d886d04134cbd?s=96&d=mm&r=g","caption":"Murielle"}}]}},"_links":{"self":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8787"}],"collection":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/comments?post=8787"}],"version-history":[{"count":2,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8787\/revisions"}],"predecessor-version":[{"id":9740,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/posts\/8787\/revisions\/9740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media\/6962"}],"wp:attachment":[{"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/media?parent=8787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/categories?post=8787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fondation-grenoble-inp.fr\/en\/wp-json\/wp\/v2\/tags?post=8787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}